{"id":39,"date":"2023-06-12T02:33:32","date_gmt":"2023-06-12T02:33:32","guid":{"rendered":"https:\/\/adnc.llc\/?page_id=39"},"modified":"2023-06-12T02:47:14","modified_gmt":"2023-06-12T02:47:14","slug":"home","status":"publish","type":"page","link":"https:\/\/adnc.llc\/es\/","title":{"rendered":"Servicios Forenses"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos una empresa l\u00edder que inici\u00f3 sus operaciones en 2012, como pioneros en el campo de los servicios forenses en Argentina. Nuestro viaje comenz\u00f3 en nuestro pa\u00eds y posteriormente se expandi\u00f3 para incluir capacitaci\u00f3n especializada y consultor\u00eda forense experta en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestros servicios incluyen consultor\u00eda forense, brindando asesor\u00eda, estudios, peritajes e investigaciones de situaciones tanto de \u00edndole penal como no penal, mediante el uso de m\u00e9todos y t\u00e9cnicas espec\u00edficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 tipo de servicios forenses ofrecemos?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Documentoscop\u00eda Forense<\/li>\n\n\n\n<li>Bal\u00edstica<\/li>\n\n\n\n<li>Investigaci\u00f3n de huellas dactilares<\/li>\n\n\n\n<li>Experiencia en escopometr\u00eda<\/li>\n\n\n\n<li>Investigaci\u00f3n de la escena del crimen<\/li>\n\n\n\n<li>Gen\u00e9tica<\/li>\n\n\n\n<li>Servicio de Control de Autenticidad de Documentos<\/li>\n\n\n\n<li>Investigaci\u00f3n de Fraude<\/li>\n\n\n\n<li>Capacitaci\u00f3n forense en \u00e1reas espec\u00edficas de criminal\u00edstica<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>We are a leading company that began its operations in 2012, as a pioneer in the field of forensic services in Argentina. Our journey started in our country and later expanded to include specialized training and expert forensic consulting around the world. Our services include forensic consultancy, providing advice, studies, expert opinions, and investigations of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-39","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":3,"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":51,"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/pages\/39\/revisions\/51"}],"wp:attachment":[{"href":"https:\/\/adnc.llc\/es\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}